{"id":976,"count":20,"description":"","link":"https:\/\/vapexyz.com\/sv\/category\/doloda-disposable-vape\/","name":"DOLODA eng\u00e5ngsvape","slug":"doloda-disposable-vape","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/vapexyz.com\/sv\/wp-json\/wp\/v2\/categories\/976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapexyz.com\/sv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/vapexyz.com\/sv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/vapexyz.com\/sv\/wp-json\/wp\/v2\/posts?categories=976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}