{"id":983,"count":8,"description":"","link":"https:\/\/vapexyz.com\/ro\/category\/vapen-disposable-vape\/","name":"Vapa de unic\u0103 folosin\u021b\u0103 VAPEN","slug":"vape-de-unica-folosinta-vape","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/vapexyz.com\/ro\/wp-json\/wp\/v2\/categories\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapexyz.com\/ro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/vapexyz.com\/ro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/vapexyz.com\/ro\/wp-json\/wp\/v2\/posts?categories=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}